{"id":12912,"date":"2026-04-21T09:57:38","date_gmt":"2026-04-21T12:57:38","guid":{"rendered":"https:\/\/golfinhorotador.org.br\/?p=12912"},"modified":"2026-04-22T10:00:06","modified_gmt":"2026-04-22T13:00:06","slug":"jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026","status":"publish","type":"post","link":"https:\/\/golfinhorotador.org.br\/en\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/","title":{"rendered":"Jornal da Ilha- Projeto Golfinho Rotador conquistou o Oscar da Sustentabilidade, na ITB Berlin 2026."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12912\" class=\"elementor elementor-12912\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9076ae e-flex e-con-boxed e-con e-parent\" data-id=\"e9076ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5558fd6 e-con-full e-flex e-con e-child\" data-id=\"5558fd6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60c763e elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"60c763e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/watch?v=_E14AEsR6BQ\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"482\" height=\"676\" src=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2026\/04\/Jornal-da-Ilha-Projeto-Golfinho-Rotador-conquistou-o-Oscar-da-Sustentabilidade-na-ITB-Berlin-2026-DESTAQUE.jpg\" class=\"attachment-full size-full wp-image-12913\" alt=\"\" srcset=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2026\/04\/Jornal-da-Ilha-Projeto-Golfinho-Rotador-conquistou-o-Oscar-da-Sustentabilidade-na-ITB-Berlin-2026-DESTAQUE.jpg 482w, https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2026\/04\/Jornal-da-Ilha-Projeto-Golfinho-Rotador-conquistou-o-Oscar-da-Sustentabilidade-na-ITB-Berlin-2026-DESTAQUE-214x300.jpg 214w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-acf6eb3 e-con-full e-flex e-con e-child\" data-id=\"acf6eb3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59fa0c1 elementor-widget elementor-widget-text-editor\" data-id=\"59fa0c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Ve\u00edculo<\/strong>: Jornal da Ilha<\/p><p><strong>Data de publica\u00e7\u00e3o<\/strong>: 21\/04\/2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-592e6b8 elementor-widget elementor-widget-video\" data-id=\"592e6b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=_E14AEsR6BQ&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ve\u00edculo: Jornal da Ilha Data de publica\u00e7\u00e3o: 21\/04\/2026<\/p>\n","protected":false},"author":2,"featured_media":12913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[71],"tags":[],"class_list":["post-12912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clipping"],"acf":{"exibir_imagem_destacada":"N\u00e3o"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jornal da Ilha- Projeto Golfinho Rotador conquistou o Oscar da Sustentabilidade, na ITB Berlin 2026. - Projeto Golfinho Rotador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jornal da Ilha- Projeto Golfinho Rotador conquistou o Oscar da Sustentabilidade, na ITB Berlin 2026. - Projeto Golfinho Rotador\" \/>\n<meta property=\"og:description\" content=\"Ve\u00edculo: Jornal da Ilha Data de publica\u00e7\u00e3o: 21\/04\/2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Projeto Golfinho Rotador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Projeto-Golfinho-Rotador-155695874539813\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-21T12:57:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T13:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2026\/04\/Jornal-da-Ilha-Projeto-Golfinho-Rotador-conquistou-o-Oscar-da-Sustentabilidade-na-ITB-Berlin-2026-DESTAQUE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"482\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Projeto Golfinho Rotador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@golfinhorotador\" \/>\n<meta name=\"twitter:site\" content=\"@golfinhorotador\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Projeto Golfinho Rotador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2026\\\/04\\\/21\\\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2026\\\/04\\\/21\\\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\\\/\"},\"author\":{\"name\":\"Projeto Golfinho Rotador\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#\\\/schema\\\/person\\\/31c9f545fc127c9e21fc1c5f001269db\"},\"headline\":\"Jornal da Ilha- Projeto Golfinho Rotador conquistou o Oscar da Sustentabilidade, na ITB Berlin 2026.\",\"datePublished\":\"2026-04-21T12:57:38+00:00\",\"dateModified\":\"2026-04-22T13:00:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2026\\\/04\\\/21\\\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\\\/\"},\"wordCount\":32,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2026\\\/04\\\/21\\\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Jornal-da-Ilha-Projeto-Golfinho-Rotador-conquistou-o-Oscar-da-Sustentabilidade-na-ITB-Berlin-2026-DESTAQUE.jpg\",\"articleSection\":[\"Clipping\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/golfinhorotador.org.br\\\/2026\\\/04\\\/21\\\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2026\\\/04\\\/21\\\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\\\/\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2026\\\/04\\\/21\\\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\\\/\",\"name\":\"Jornal da Ilha- Projeto Golfinho Rotador conquistou o Oscar da Sustentabilidade, na ITB Berlin 2026. - Projeto Golfinho Rotador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2026\\\/04\\\/21\\\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2026\\\/04\\\/21\\\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Jornal-da-Ilha-Projeto-Golfinho-Rotador-conquistou-o-Oscar-da-Sustentabilidade-na-ITB-Berlin-2026-DESTAQUE.jpg\",\"datePublished\":\"2026-04-21T12:57:38+00:00\",\"dateModified\":\"2026-04-22T13:00:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2026\\\/04\\\/21\\\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/golfinhorotador.org.br\\\/2026\\\/04\\\/21\\\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2026\\\/04\\\/21\\\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Jornal-da-Ilha-Projeto-Golfinho-Rotador-conquistou-o-Oscar-da-Sustentabilidade-na-ITB-Berlin-2026-DESTAQUE.jpg\",\"contentUrl\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Jornal-da-Ilha-Projeto-Golfinho-Rotador-conquistou-o-Oscar-da-Sustentabilidade-na-ITB-Berlin-2026-DESTAQUE.jpg\",\"width\":482,\"height\":676},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2026\\\/04\\\/21\\\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/golfinhorotador.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jornal da Ilha- Projeto Golfinho Rotador conquistou o Oscar da Sustentabilidade, na ITB Berlin 2026.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#website\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/\",\"name\":\"Projeto Golfinho Rotador\",\"description\":\"Fernando de Noronha\",\"publisher\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/golfinhorotador.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#organization\",\"name\":\"Projeto Golfinho Rotador\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-PGR-2025-512.png\",\"contentUrl\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-PGR-2025-512.png\",\"width\":512,\"height\":512,\"caption\":\"Projeto Golfinho Rotador\"},\"image\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Projeto-Golfinho-Rotador-155695874539813\",\"https:\\\/\\\/x.com\\\/golfinhorotador\",\"https:\\\/\\\/www.instagram.com\\\/golfinhorotador\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCYw-aMfBHbkUU_DimpWJzbw\",\"https:\\\/\\\/www.tiktok.com\\\/@golfinhorotador\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#\\\/schema\\\/person\\\/31c9f545fc127c9e21fc1c5f001269db\",\"name\":\"Projeto Golfinho Rotador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g\",\"caption\":\"Projeto Golfinho Rotador\"},\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/en\\\/author\\\/projeto-golfinho-rotador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jornal da Ilha- Projeto Golfinho Rotador conquistou o Oscar da Sustentabilidade, na ITB Berlin 2026. - Projeto Golfinho Rotador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/","og_locale":"en_US","og_type":"article","og_title":"Jornal da Ilha- Projeto Golfinho Rotador conquistou o Oscar da Sustentabilidade, na ITB Berlin 2026. - Projeto Golfinho Rotador","og_description":"Ve\u00edculo: Jornal da Ilha Data de publica\u00e7\u00e3o: 21\/04\/2026","og_url":"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/","og_site_name":"Projeto Golfinho Rotador","article_publisher":"https:\/\/www.facebook.com\/Projeto-Golfinho-Rotador-155695874539813","article_published_time":"2026-04-21T12:57:38+00:00","article_modified_time":"2026-04-22T13:00:06+00:00","og_image":[{"width":482,"height":676,"url":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2026\/04\/Jornal-da-Ilha-Projeto-Golfinho-Rotador-conquistou-o-Oscar-da-Sustentabilidade-na-ITB-Berlin-2026-DESTAQUE.jpg","type":"image\/jpeg"}],"author":"Projeto Golfinho Rotador","twitter_card":"summary_large_image","twitter_creator":"@golfinhorotador","twitter_site":"@golfinhorotador","twitter_misc":{"Written by":"Projeto Golfinho Rotador","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/#article","isPartOf":{"@id":"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/"},"author":{"name":"Projeto Golfinho Rotador","@id":"https:\/\/golfinhorotador.org.br\/#\/schema\/person\/31c9f545fc127c9e21fc1c5f001269db"},"headline":"Jornal da Ilha- Projeto Golfinho Rotador conquistou o Oscar da Sustentabilidade, na ITB Berlin 2026.","datePublished":"2026-04-21T12:57:38+00:00","dateModified":"2026-04-22T13:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/"},"wordCount":32,"commentCount":0,"publisher":{"@id":"https:\/\/golfinhorotador.org.br\/#organization"},"image":{"@id":"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2026\/04\/Jornal-da-Ilha-Projeto-Golfinho-Rotador-conquistou-o-Oscar-da-Sustentabilidade-na-ITB-Berlin-2026-DESTAQUE.jpg","articleSection":["Clipping"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/","url":"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/","name":"Jornal da Ilha- Projeto Golfinho Rotador conquistou o Oscar da Sustentabilidade, na ITB Berlin 2026. - Projeto Golfinho Rotador","isPartOf":{"@id":"https:\/\/golfinhorotador.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/#primaryimage"},"image":{"@id":"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2026\/04\/Jornal-da-Ilha-Projeto-Golfinho-Rotador-conquistou-o-Oscar-da-Sustentabilidade-na-ITB-Berlin-2026-DESTAQUE.jpg","datePublished":"2026-04-21T12:57:38+00:00","dateModified":"2026-04-22T13:00:06+00:00","breadcrumb":{"@id":"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/#primaryimage","url":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2026\/04\/Jornal-da-Ilha-Projeto-Golfinho-Rotador-conquistou-o-Oscar-da-Sustentabilidade-na-ITB-Berlin-2026-DESTAQUE.jpg","contentUrl":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2026\/04\/Jornal-da-Ilha-Projeto-Golfinho-Rotador-conquistou-o-Oscar-da-Sustentabilidade-na-ITB-Berlin-2026-DESTAQUE.jpg","width":482,"height":676},{"@type":"BreadcrumbList","@id":"https:\/\/golfinhorotador.org.br\/2026\/04\/21\/jornal-da-ilha-projeto-golfinho-rotador-conquistou-o-oscar-da-sustentabilidade-na-itb-berlin-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/golfinhorotador.org.br\/"},{"@type":"ListItem","position":2,"name":"Jornal da Ilha- Projeto Golfinho Rotador conquistou o Oscar da Sustentabilidade, na ITB Berlin 2026."}]},{"@type":"WebSite","@id":"https:\/\/golfinhorotador.org.br\/#website","url":"https:\/\/golfinhorotador.org.br\/","name":"Projeto Golfinho Rotador","description":"Fernando de Noronha","publisher":{"@id":"https:\/\/golfinhorotador.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/golfinhorotador.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/golfinhorotador.org.br\/#organization","name":"Projeto Golfinho Rotador","url":"https:\/\/golfinhorotador.org.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/golfinhorotador.org.br\/#\/schema\/logo\/image\/","url":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/07\/Logo-PGR-2025-512.png","contentUrl":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/07\/Logo-PGR-2025-512.png","width":512,"height":512,"caption":"Projeto Golfinho Rotador"},"image":{"@id":"https:\/\/golfinhorotador.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Projeto-Golfinho-Rotador-155695874539813","https:\/\/x.com\/golfinhorotador","https:\/\/www.instagram.com\/golfinhorotador\/","https:\/\/www.youtube.com\/channel\/UCYw-aMfBHbkUU_DimpWJzbw","https:\/\/www.tiktok.com\/@golfinhorotador"]},{"@type":"Person","@id":"https:\/\/golfinhorotador.org.br\/#\/schema\/person\/31c9f545fc127c9e21fc1c5f001269db","name":"Projeto Golfinho Rotador","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g","caption":"Projeto Golfinho Rotador"},"url":"https:\/\/golfinhorotador.org.br\/en\/author\/projeto-golfinho-rotador\/"}]}},"_links":{"self":[{"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts\/12912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/comments?post=12912"}],"version-history":[{"count":8,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts\/12912\/revisions"}],"predecessor-version":[{"id":12922,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts\/12912\/revisions\/12922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/media\/12913"}],"wp:attachment":[{"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/media?parent=12912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/categories?post=12912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/tags?post=12912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}