{"id":3440,"date":"2022-12-14T18:53:18","date_gmt":"2022-12-14T21:53:18","guid":{"rendered":"https:\/\/golfinhorotador.org.br\/?p=3440"},"modified":"2025-08-11T19:04:32","modified_gmt":"2025-08-11T22:04:32","slug":"pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo","status":"publish","type":"post","link":"https:\/\/golfinhorotador.org.br\/en\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/","title":{"rendered":"Pesquisa conclui que diversidade gen\u00e9tica dos golfinhos de Fernando de Noronha est\u00e1 diminuindo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3440\" class=\"elementor elementor-3440\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fb408f2 e-flex e-con-boxed e-con e-parent\" data-id=\"3fb408f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ad15a6 elementor-widget elementor-widget-gallery\" data-id=\"7ad15a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;image_hover_animation&quot;:&quot;grow&quot;,&quot;gallery_layout&quot;:&quot;justified&quot;,&quot;ideal_row_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:331,&quot;sizes&quot;:[]},&quot;lazyload&quot;:&quot;yes&quot;,&quot;ideal_row_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;ideal_row_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-00001.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7ad15a6\" data-elementor-lightbox-title=\"PGR-DNA-00001\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzQ0MSwidXJsIjoiaHR0cHM6XC9cL2dvbGZpbmhvcm90YWRvci5vcmcuYnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9QR1ItRE5BLTAwMDAxLmpwZyIsInNsaWRlc2hvdyI6IjdhZDE1YTYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-00001.jpg\" data-width=\"768\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-00002.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7ad15a6\" data-elementor-lightbox-title=\"PGR-DNA-00002\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzQ0MiwidXJsIjoiaHR0cHM6XC9cL2dvbGZpbmhvcm90YWRvci5vcmcuYnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9QR1ItRE5BLTAwMDAyLmpwZyIsInNsaWRlc2hvdyI6IjdhZDE1YTYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-00002.jpg\" data-width=\"768\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-00003.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7ad15a6\" data-elementor-lightbox-title=\"PGR-DNA-00003\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzQ0MywidXJsIjoiaHR0cHM6XC9cL2dvbGZpbmhvcm90YWRvci5vcmcuYnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9QR1ItRE5BLTAwMDAzLmpwZyIsInNsaWRlc2hvdyI6IjdhZDE1YTYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-00003.jpg\" data-width=\"768\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-00004.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7ad15a6\" data-elementor-lightbox-title=\"PGR-DNA-00004\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzQ0NCwidXJsIjoiaHR0cHM6XC9cL2dvbGZpbmhvcm90YWRvci5vcmcuYnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9QR1ItRE5BLTAwMDA0LmpwZyIsInNsaWRlc2hvdyI6IjdhZDE1YTYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-00004.jpg\" data-width=\"819\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-00005.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7ad15a6\" data-elementor-lightbox-title=\"PGR-DNA-00005\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzQ0NSwidXJsIjoiaHR0cHM6XC9cL2dvbGZpbmhvcm90YWRvci5vcmcuYnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9QR1ItRE5BLTAwMDA1LmpwZyIsInNsaWRlc2hvdyI6IjdhZDE1YTYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-00005.jpg\" data-width=\"819\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-00006.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7ad15a6\" data-elementor-lightbox-title=\"PGR-DNA-00006\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzQ0NiwidXJsIjoiaHR0cHM6XC9cL2dvbGZpbmhvcm90YWRvci5vcmcuYnJcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzA4XC9QR1ItRE5BLTAwMDA2LmpwZyIsInNsaWRlc2hvdyI6IjdhZDE1YTYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-00006.jpg\" data-width=\"1024\" data-height=\"768\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a0a070e elementor-widget elementor-widget-text-editor\" data-id=\"3a0a070e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Estudos realizados por pesquisadores da Universidade Federal do Esp\u00edrito Santo (<a href=\"https:\/\/g1.globo.com\/educacao\/universidade\/ufes\/\" target=\"_blank\" rel=\"noreferrer noopener\">UFES<\/a>), em parceria com o Centro Golfinho Rotador, chegaram a uma conclus\u00e3o preocupante. A partir de amostras do DNA de golfinhos-rotadores em Fernando de Noronha, os especialistas identificaram uma redu\u00e7\u00e3o na diversidade gen\u00e9tica dos animais que vivem no arquip\u00e9lago pernambucano. Para a Dra. Ana Paula Farro, professora da UFES, esse fato representa um s\u00e9rio risco para a popula\u00e7\u00e3o de golfinho-rotador de Noronha e refor\u00e7a a necessidade de conserva\u00e7\u00e3o do habitat da esp\u00e9cie. Iniciado em 2004, o monitoramento gen\u00e9tico dos golfinhos-rotadores de Fernando de Noronha \u00e9 um dos mais longos do mundo para golfinhos, que conta com o patroc\u00ednio da Petrobras por meio do Programa Petrobras Socioambiental.<\/p><p>Os estudos mais recentes evidenciam uma queda na diversidade gen\u00e9tica dos animais. \u201cQuando come\u00e7amos nossa pesquisa, detectamos duas linhagens principais, sendo que uma delas representava cerca de 75% do total da popula\u00e7\u00e3o avaliada. Em 2019 essa linhagem j\u00e1 representava em torno de 95% dos animais, mostrando uma diminui\u00e7\u00e3o da diversidade gen\u00e9tica e uma homogeneiza\u00e7\u00e3o da popula\u00e7\u00e3o\u201d, disse Dra. Ana Paula. Ela ainda explicou que os resultados das pesquisas sugerem a exist\u00eancia de golfinhos residentes em Noronha, de uma linhagem exclusiva do local, e que animais de outras localidades tamb\u00e9m frequentam o arquip\u00e9lago. \u201cQuanto mais parecidos geneticamente, menor diversidade. Com a queda na diversidade gen\u00e9tica, precisamos ficar mais atentos \u00e0s popula\u00e7\u00f5es de golfinhos, pois eles podem n\u00e3o responder positivamente \u00e0s press\u00f5es ambientais, podendo apresentar doen\u00e7as e\/ou outros problemas\u201d.<\/p><p>Segundo a bi\u00f3loga, a diminui\u00e7\u00e3o na diversidade gen\u00e9tica representa riscos para os golfinhos, j\u00e1 que quanto maior a variabilidade gen\u00e9tica, maior \u00e9 a chance de esses animais terem sucesso. \u201c\u00c9 necess\u00e1ria uma diferencia\u00e7\u00e3o gen\u00e9tica para os indiv\u00edduos serem mantidos no ambiente\u201d, disse Ana Paula. Ela usou como exemplo a import\u00e2ncia da varia\u00e7\u00e3o gen\u00e9tica na pandemia de Covid-19. \u201cEm rela\u00e7\u00e3o ao coronav\u00edrus, tivemos diferentes respostas a essa doen\u00e7a. Se todos os humanos fossem geneticamente iguais, ir\u00edamos todos responder da mesma forma. O mesmo racioc\u00ednio vale para os golfinhos. De uma forma simplificada, aquele que tiver melhor resposta, tem maior chance permanecer na popula\u00e7\u00e3o\u201d.<\/p><p>De acordo com a pesquisadora, a melhor maneira de assegurar a exist\u00eancia dos golfinhos \u00e9 conservar o meio ambiente. \u201cTemos de preservar a Natureza. No caso dos golfinhos-rotadores de Noronha, \u00e9 preciso conservar a regi\u00e3o do arquip\u00e9lago\u201d, destaca Ana Paula. Para ela, algumas das atitudes importantes nesse sentido seriam produzir menos lixo, evitar contaminantes na \u00e1gua e gerar menos estresse na \u00e1rea, para os golfinhos permanecerem na regi\u00e3o e poderem se reproduzir e com o tempo talvez aumentar a variabilidade gen\u00e9tica.<\/p><h5><strong>M\u00e9todo de Trabalho<\/strong><\/h5><p>A pesquisa \u00e9 feita a partir da coleta de amostras dos golfinhos da ilha, realizada com o uso de uma esponja e um leve toque na pele do animal. \u201cApenas passamos a esponja no dorso dos golfinhos. A pele deles sai facilmente com o contato e fica aderida\u201d. O processo dura poucos segundos e n\u00e3o causa dor aos golfinhos. Durante essa fase dos estudos, os pesquisadores coletaram em Noronha por uma semana. Nesse per\u00edodo, obtiveram 94 amostras, a partir das quais conseguem extrair o DNA dos animais.<\/p><p>\u201cCom isso, avaliamos as semelhan\u00e7as e diferen\u00e7as gen\u00e9ticas dos animais\u201d, disse a bi\u00f3loga, acrescentando que essas amostras ser\u00e3o analisadas no Laborat\u00f3rio de Gen\u00e9tica e Conserva\u00e7\u00e3o da UFES. Ana Paula ainda falou sobre a import\u00e2ncia desse trabalho ser realizado com o apoio do Projeto Golfinho Rotador. \u201cEssa parceria \u00e9 fundamental para os nossos estudos, pois nos proporciona uma excelente oportunidade de monitoramento gen\u00e9tico ao longo do tempo. O golfinho tem uma vida longa \u2013 pode viver at\u00e9 35 anos \u2013 e sua diversidade gen\u00e9tica deve ser estudada a m\u00e9dio e longo prazo. Isso \u00e9 essencial para entender a gen\u00e9tica e din\u00e2mica populacional da esp\u00e9cie na regi\u00e3o\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-655dddb elementor-widget elementor-widget-video\" data-id=\"655dddb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Estudos realizados por pesquisadores da Universidade Federal do Esp\u00edrito Santo (UFES), em parceria com o Centro Golfinho Rotador, chegaram a uma conclus\u00e3o preocupante. A partir de amostras do DNA de golfinhos-rotadores em Fernando de Noronha, os especialistas identificaram uma redu\u00e7\u00e3o na diversidade gen\u00e9tica dos animais que vivem no arquip\u00e9lago pernambucano. Para a Dra. Ana Paula [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":{"exibir_imagem_destacada":"N\u00e3o"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pesquisa conclui que diversidade gen\u00e9tica dos golfinhos de Fernando de Noronha est\u00e1 diminuindo - Projeto Golfinho Rotador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pesquisa conclui que diversidade gen\u00e9tica dos golfinhos de Fernando de Noronha est\u00e1 diminuindo - Projeto Golfinho Rotador\" \/>\n<meta property=\"og:description\" content=\"Estudos realizados por pesquisadores da Universidade Federal do Esp\u00edrito Santo (UFES), em parceria com o Centro Golfinho Rotador, chegaram a uma conclus\u00e3o preocupante. A partir de amostras do DNA de golfinhos-rotadores em Fernando de Noronha, os especialistas identificaram uma redu\u00e7\u00e3o na diversidade gen\u00e9tica dos animais que vivem no arquip\u00e9lago pernambucano. Para a Dra. Ana Paula [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/\" \/>\n<meta property=\"og:site_name\" content=\"Projeto Golfinho Rotador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Projeto-Golfinho-Rotador-155695874539813\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-14T21:53:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-11T22:04:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-capa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Projeto Golfinho Rotador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@golfinhorotador\" \/>\n<meta name=\"twitter:site\" content=\"@golfinhorotador\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Projeto Golfinho Rotador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2022\\\/12\\\/14\\\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2022\\\/12\\\/14\\\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\\\/\"},\"author\":{\"name\":\"Projeto Golfinho Rotador\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#\\\/schema\\\/person\\\/31c9f545fc127c9e21fc1c5f001269db\"},\"headline\":\"Pesquisa conclui que diversidade gen\u00e9tica dos golfinhos de Fernando de Noronha est\u00e1 diminuindo\",\"datePublished\":\"2022-12-14T21:53:18+00:00\",\"dateModified\":\"2025-08-11T22:04:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2022\\\/12\\\/14\\\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\\\/\"},\"wordCount\":696,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2022\\\/12\\\/14\\\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PGR-DNA-capa.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/golfinhorotador.org.br\\\/2022\\\/12\\\/14\\\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2022\\\/12\\\/14\\\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\\\/\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2022\\\/12\\\/14\\\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\\\/\",\"name\":\"Pesquisa conclui que diversidade gen\u00e9tica dos golfinhos de Fernando de Noronha est\u00e1 diminuindo - Projeto Golfinho Rotador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2022\\\/12\\\/14\\\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2022\\\/12\\\/14\\\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PGR-DNA-capa.jpg\",\"datePublished\":\"2022-12-14T21:53:18+00:00\",\"dateModified\":\"2025-08-11T22:04:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2022\\\/12\\\/14\\\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/golfinhorotador.org.br\\\/2022\\\/12\\\/14\\\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2022\\\/12\\\/14\\\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PGR-DNA-capa.jpg\",\"contentUrl\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PGR-DNA-capa.jpg\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2022\\\/12\\\/14\\\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/golfinhorotador.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pesquisa conclui que diversidade gen\u00e9tica dos golfinhos de Fernando de Noronha est\u00e1 diminuindo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#website\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/\",\"name\":\"Projeto Golfinho Rotador\",\"description\":\"Fernando de Noronha\",\"publisher\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/golfinhorotador.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#organization\",\"name\":\"Projeto Golfinho Rotador\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-PGR-2025-512.png\",\"contentUrl\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-PGR-2025-512.png\",\"width\":512,\"height\":512,\"caption\":\"Projeto Golfinho Rotador\"},\"image\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Projeto-Golfinho-Rotador-155695874539813\",\"https:\\\/\\\/x.com\\\/golfinhorotador\",\"https:\\\/\\\/www.instagram.com\\\/golfinhorotador\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCYw-aMfBHbkUU_DimpWJzbw\",\"https:\\\/\\\/www.tiktok.com\\\/@golfinhorotador\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#\\\/schema\\\/person\\\/31c9f545fc127c9e21fc1c5f001269db\",\"name\":\"Projeto Golfinho Rotador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g\",\"caption\":\"Projeto Golfinho Rotador\"},\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/en\\\/author\\\/projeto-golfinho-rotador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pesquisa conclui que diversidade gen\u00e9tica dos golfinhos de Fernando de Noronha est\u00e1 diminuindo - Projeto Golfinho Rotador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/","og_locale":"en_US","og_type":"article","og_title":"Pesquisa conclui que diversidade gen\u00e9tica dos golfinhos de Fernando de Noronha est\u00e1 diminuindo - Projeto Golfinho Rotador","og_description":"Estudos realizados por pesquisadores da Universidade Federal do Esp\u00edrito Santo (UFES), em parceria com o Centro Golfinho Rotador, chegaram a uma conclus\u00e3o preocupante. A partir de amostras do DNA de golfinhos-rotadores em Fernando de Noronha, os especialistas identificaram uma redu\u00e7\u00e3o na diversidade gen\u00e9tica dos animais que vivem no arquip\u00e9lago pernambucano. Para a Dra. Ana Paula [&hellip;]","og_url":"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/","og_site_name":"Projeto Golfinho Rotador","article_publisher":"https:\/\/www.facebook.com\/Projeto-Golfinho-Rotador-155695874539813","article_published_time":"2022-12-14T21:53:18+00:00","article_modified_time":"2025-08-11T22:04:32+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-capa.jpg","type":"image\/jpeg"}],"author":"Projeto Golfinho Rotador","twitter_card":"summary_large_image","twitter_creator":"@golfinhorotador","twitter_site":"@golfinhorotador","twitter_misc":{"Written by":"Projeto Golfinho Rotador","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/#article","isPartOf":{"@id":"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/"},"author":{"name":"Projeto Golfinho Rotador","@id":"https:\/\/golfinhorotador.org.br\/#\/schema\/person\/31c9f545fc127c9e21fc1c5f001269db"},"headline":"Pesquisa conclui que diversidade gen\u00e9tica dos golfinhos de Fernando de Noronha est\u00e1 diminuindo","datePublished":"2022-12-14T21:53:18+00:00","dateModified":"2025-08-11T22:04:32+00:00","mainEntityOfPage":{"@id":"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/"},"wordCount":696,"commentCount":0,"publisher":{"@id":"https:\/\/golfinhorotador.org.br\/#organization"},"image":{"@id":"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/#primaryimage"},"thumbnailUrl":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-capa.jpg","articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/","url":"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/","name":"Pesquisa conclui que diversidade gen\u00e9tica dos golfinhos de Fernando de Noronha est\u00e1 diminuindo - Projeto Golfinho Rotador","isPartOf":{"@id":"https:\/\/golfinhorotador.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/#primaryimage"},"image":{"@id":"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/#primaryimage"},"thumbnailUrl":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-capa.jpg","datePublished":"2022-12-14T21:53:18+00:00","dateModified":"2025-08-11T22:04:32+00:00","breadcrumb":{"@id":"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/#primaryimage","url":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-capa.jpg","contentUrl":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR-DNA-capa.jpg","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/golfinhorotador.org.br\/2022\/12\/14\/pesquisa-conclui-que-diversidade-genetica-dos-golfinhos-de-fernando-de-noronha-esta-diminuindo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/golfinhorotador.org.br\/"},{"@type":"ListItem","position":2,"name":"Pesquisa conclui que diversidade gen\u00e9tica dos golfinhos de Fernando de Noronha est\u00e1 diminuindo"}]},{"@type":"WebSite","@id":"https:\/\/golfinhorotador.org.br\/#website","url":"https:\/\/golfinhorotador.org.br\/","name":"Projeto Golfinho Rotador","description":"Fernando de Noronha","publisher":{"@id":"https:\/\/golfinhorotador.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/golfinhorotador.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/golfinhorotador.org.br\/#organization","name":"Projeto Golfinho Rotador","url":"https:\/\/golfinhorotador.org.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/golfinhorotador.org.br\/#\/schema\/logo\/image\/","url":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/07\/Logo-PGR-2025-512.png","contentUrl":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/07\/Logo-PGR-2025-512.png","width":512,"height":512,"caption":"Projeto Golfinho Rotador"},"image":{"@id":"https:\/\/golfinhorotador.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Projeto-Golfinho-Rotador-155695874539813","https:\/\/x.com\/golfinhorotador","https:\/\/www.instagram.com\/golfinhorotador\/","https:\/\/www.youtube.com\/channel\/UCYw-aMfBHbkUU_DimpWJzbw","https:\/\/www.tiktok.com\/@golfinhorotador"]},{"@type":"Person","@id":"https:\/\/golfinhorotador.org.br\/#\/schema\/person\/31c9f545fc127c9e21fc1c5f001269db","name":"Projeto Golfinho Rotador","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g","caption":"Projeto Golfinho Rotador"},"url":"https:\/\/golfinhorotador.org.br\/en\/author\/projeto-golfinho-rotador\/"}]}},"_links":{"self":[{"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts\/3440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/comments?post=3440"}],"version-history":[{"count":4,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts\/3440\/revisions"}],"predecessor-version":[{"id":3453,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts\/3440\/revisions\/3453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/media\/3447"}],"wp:attachment":[{"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/media?parent=3440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/categories?post=3440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/tags?post=3440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}