{"id":874,"date":"2016-06-08T18:59:16","date_gmt":"2016-06-08T21:59:16","guid":{"rendered":"https:\/\/golfinhorotador.org.br\/?p=874"},"modified":"2025-08-06T19:01:56","modified_gmt":"2025-08-06T22:01:56","slug":"dia-mundial-dos-oceanos-8-de-junho","status":"publish","type":"post","link":"https:\/\/golfinhorotador.org.br\/en\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/","title":{"rendered":"Dia Mundial dos Oceanos: 8 de Junho"},"content":{"rendered":"<p>O Dia Mundial dos Oceanos come\u00e7ou a ser comemorado em 8 de Junho de 1992 durante a Rio-92 na cidade do Rio de Janeiro. Hoje falaremos um pouco sobre mares e oceanos.<\/p>\n<p>&nbsp;<\/p>\n<p>Os mares e oceanos cobrem 70% do planeta e s\u00e3o 90% da biosfera, que \u00e9 o conjunto de todas as partes do planeta Terra onde existe ou pode existir vida. E essa vida nos mares e oceanos, assim como os processos ambientais geol\u00f3gicos e f\u00edsicos t\u00eam grande complexidade, principalmente por causa do elemento \u00e1gua, que possibilita maior\u00a0conectividade nas tr\u00eas dimens\u00f5es espaciais.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-875 size-full\" src=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/oceano-1000.jpg\" alt=\"\" width=\"1000\" height=\"667\" srcset=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/oceano-1000.jpg 1000w, https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/oceano-1000-300x200.jpg 300w, https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/oceano-1000-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Os conceitos de mares e oceanos se sobrep\u00f5em e se confundem, mas a distin\u00e7\u00e3o entre eles \u00e9 importante e est\u00e1 baseada principalmente em dois crit\u00e9rios: extens\u00e3o territorial e profundidade.<\/p>\n<p>&nbsp;<\/p>\n<p>Oceanos s\u00e3o profundos, ocupam grandes extens\u00f5es e sempre t\u00eam livre circula\u00e7\u00e3o. Sua profundidade m\u00e9dia \u00e9 de 3.300 metros, e a maior conhecida \u00e9 a de 11.000 metros na Fossa das Marianas (Oceano Pac\u00edfico Norte). S\u00e3o tr\u00eas os oceanos na Terra: Atl\u00e2ntico, Pac\u00edfico e \u00cdndico. O Oceano que banha o Brasil \u00e9 o Atl\u00e2ntico.<\/p>\n<p>&nbsp;<\/p>\n<p>Os mares possuem profundidade m\u00e9dia abaixo de 1.000 metros, s\u00e3o menores e delimitados, total ou parcialmente, por continentes. A maioria dos mares faz parte dos Oceanos. Existem tr\u00eas tipos principais de mares: os abertos, que possuem uma ampla liga\u00e7\u00e3o com os oceanos; os continentais, que possuem uma liga\u00e7\u00e3o muito restrita com os oceanos; os fechados, que se ligam \u00e0s \u00e1guas oce\u00e2nicas apenas indiretamente atrav\u00e9s de canais e rios. Existem dezenas de mares, mas nenhum no Brasil.<\/p>\n<p>&nbsp;<\/p>\n<p>A forma\u00e7\u00e3o dos mares e oceanos atuais \u00e9 resultante do deslocamento dos continentes sobre o magma, uma massa de aspecto pastoso localizada no interior da Terra.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/golfinhorotador.org.br\/2016\/04\/04\/25-anos-do-projeto-golfinho-rotador\/\">Assista o oocument\u00e1rio Projeto Golfinho Rotador 25 Anos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Dia Mundial dos Oceanos come\u00e7ou a ser comemorado em 8 de Junho de 1992 durante a Rio-92 na cidade do Rio de Janeiro. Hoje falaremos um pouco sobre mares e oceanos. &nbsp; Os mares e oceanos cobrem 70% do planeta e s\u00e3o 90% da biosfera, que \u00e9 o conjunto de todas as partes do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":875,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":{"exibir_imagem_destacada":"Sim"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dia Mundial dos Oceanos: 8 de Junho - Projeto Golfinho Rotador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dia Mundial dos Oceanos: 8 de Junho - Projeto Golfinho Rotador\" \/>\n<meta property=\"og:description\" content=\"O Dia Mundial dos Oceanos come\u00e7ou a ser comemorado em 8 de Junho de 1992 durante a Rio-92 na cidade do Rio de Janeiro. Hoje falaremos um pouco sobre mares e oceanos. &nbsp; Os mares e oceanos cobrem 70% do planeta e s\u00e3o 90% da biosfera, que \u00e9 o conjunto de todas as partes do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/\" \/>\n<meta property=\"og:site_name\" content=\"Projeto Golfinho Rotador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Projeto-Golfinho-Rotador-155695874539813\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-08T21:59:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-06T22:01:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/oceano-1000.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Projeto Golfinho Rotador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@golfinhorotador\" \/>\n<meta name=\"twitter:site\" content=\"@golfinhorotador\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Projeto Golfinho Rotador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2016\\\/06\\\/08\\\/dia-mundial-dos-oceanos-8-de-junho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2016\\\/06\\\/08\\\/dia-mundial-dos-oceanos-8-de-junho\\\/\"},\"author\":{\"name\":\"Projeto Golfinho Rotador\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#\\\/schema\\\/person\\\/31c9f545fc127c9e21fc1c5f001269db\"},\"headline\":\"Dia Mundial dos Oceanos: 8 de Junho\",\"datePublished\":\"2016-06-08T21:59:16+00:00\",\"dateModified\":\"2025-08-06T22:01:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2016\\\/06\\\/08\\\/dia-mundial-dos-oceanos-8-de-junho\\\/\"},\"wordCount\":314,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2016\\\/06\\\/08\\\/dia-mundial-dos-oceanos-8-de-junho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/oceano-1000.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/golfinhorotador.org.br\\\/2016\\\/06\\\/08\\\/dia-mundial-dos-oceanos-8-de-junho\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2016\\\/06\\\/08\\\/dia-mundial-dos-oceanos-8-de-junho\\\/\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2016\\\/06\\\/08\\\/dia-mundial-dos-oceanos-8-de-junho\\\/\",\"name\":\"Dia Mundial dos Oceanos: 8 de Junho - Projeto Golfinho Rotador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2016\\\/06\\\/08\\\/dia-mundial-dos-oceanos-8-de-junho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2016\\\/06\\\/08\\\/dia-mundial-dos-oceanos-8-de-junho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/oceano-1000.jpg\",\"datePublished\":\"2016-06-08T21:59:16+00:00\",\"dateModified\":\"2025-08-06T22:01:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2016\\\/06\\\/08\\\/dia-mundial-dos-oceanos-8-de-junho\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/golfinhorotador.org.br\\\/2016\\\/06\\\/08\\\/dia-mundial-dos-oceanos-8-de-junho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2016\\\/06\\\/08\\\/dia-mundial-dos-oceanos-8-de-junho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/oceano-1000.jpg\",\"contentUrl\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/oceano-1000.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/2016\\\/06\\\/08\\\/dia-mundial-dos-oceanos-8-de-junho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/golfinhorotador.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dia Mundial dos Oceanos: 8 de Junho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#website\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/\",\"name\":\"Projeto Golfinho Rotador\",\"description\":\"Fernando de Noronha\",\"publisher\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/golfinhorotador.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#organization\",\"name\":\"Projeto Golfinho Rotador\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-PGR-2025-512.png\",\"contentUrl\":\"https:\\\/\\\/golfinhorotador.org.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-PGR-2025-512.png\",\"width\":512,\"height\":512,\"caption\":\"Projeto Golfinho Rotador\"},\"image\":{\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Projeto-Golfinho-Rotador-155695874539813\",\"https:\\\/\\\/x.com\\\/golfinhorotador\",\"https:\\\/\\\/www.instagram.com\\\/golfinhorotador\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCYw-aMfBHbkUU_DimpWJzbw\",\"https:\\\/\\\/www.tiktok.com\\\/@golfinhorotador\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/golfinhorotador.org.br\\\/#\\\/schema\\\/person\\\/31c9f545fc127c9e21fc1c5f001269db\",\"name\":\"Projeto Golfinho Rotador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g\",\"caption\":\"Projeto Golfinho Rotador\"},\"url\":\"https:\\\/\\\/golfinhorotador.org.br\\\/en\\\/author\\\/projeto-golfinho-rotador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dia Mundial dos Oceanos: 8 de Junho - Projeto Golfinho Rotador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/","og_locale":"en_US","og_type":"article","og_title":"Dia Mundial dos Oceanos: 8 de Junho - Projeto Golfinho Rotador","og_description":"O Dia Mundial dos Oceanos come\u00e7ou a ser comemorado em 8 de Junho de 1992 durante a Rio-92 na cidade do Rio de Janeiro. Hoje falaremos um pouco sobre mares e oceanos. &nbsp; Os mares e oceanos cobrem 70% do planeta e s\u00e3o 90% da biosfera, que \u00e9 o conjunto de todas as partes do [&hellip;]","og_url":"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/","og_site_name":"Projeto Golfinho Rotador","article_publisher":"https:\/\/www.facebook.com\/Projeto-Golfinho-Rotador-155695874539813","article_published_time":"2016-06-08T21:59:16+00:00","article_modified_time":"2025-08-06T22:01:56+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/oceano-1000.jpg","type":"image\/jpeg"}],"author":"Projeto Golfinho Rotador","twitter_card":"summary_large_image","twitter_creator":"@golfinhorotador","twitter_site":"@golfinhorotador","twitter_misc":{"Written by":"Projeto Golfinho Rotador","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/#article","isPartOf":{"@id":"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/"},"author":{"name":"Projeto Golfinho Rotador","@id":"https:\/\/golfinhorotador.org.br\/#\/schema\/person\/31c9f545fc127c9e21fc1c5f001269db"},"headline":"Dia Mundial dos Oceanos: 8 de Junho","datePublished":"2016-06-08T21:59:16+00:00","dateModified":"2025-08-06T22:01:56+00:00","mainEntityOfPage":{"@id":"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/"},"wordCount":314,"commentCount":0,"publisher":{"@id":"https:\/\/golfinhorotador.org.br\/#organization"},"image":{"@id":"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/#primaryimage"},"thumbnailUrl":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/oceano-1000.jpg","articleSection":["Not\u00edcias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/","url":"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/","name":"Dia Mundial dos Oceanos: 8 de Junho - Projeto Golfinho Rotador","isPartOf":{"@id":"https:\/\/golfinhorotador.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/#primaryimage"},"image":{"@id":"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/#primaryimage"},"thumbnailUrl":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/oceano-1000.jpg","datePublished":"2016-06-08T21:59:16+00:00","dateModified":"2025-08-06T22:01:56+00:00","breadcrumb":{"@id":"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/#primaryimage","url":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/oceano-1000.jpg","contentUrl":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/oceano-1000.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/golfinhorotador.org.br\/2016\/06\/08\/dia-mundial-dos-oceanos-8-de-junho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/golfinhorotador.org.br\/"},{"@type":"ListItem","position":2,"name":"Dia Mundial dos Oceanos: 8 de Junho"}]},{"@type":"WebSite","@id":"https:\/\/golfinhorotador.org.br\/#website","url":"https:\/\/golfinhorotador.org.br\/","name":"Projeto Golfinho Rotador","description":"Fernando de Noronha","publisher":{"@id":"https:\/\/golfinhorotador.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/golfinhorotador.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/golfinhorotador.org.br\/#organization","name":"Projeto Golfinho Rotador","url":"https:\/\/golfinhorotador.org.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/golfinhorotador.org.br\/#\/schema\/logo\/image\/","url":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/07\/Logo-PGR-2025-512.png","contentUrl":"https:\/\/golfinhorotador.org.br\/wp-content\/uploads\/2025\/07\/Logo-PGR-2025-512.png","width":512,"height":512,"caption":"Projeto Golfinho Rotador"},"image":{"@id":"https:\/\/golfinhorotador.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Projeto-Golfinho-Rotador-155695874539813","https:\/\/x.com\/golfinhorotador","https:\/\/www.instagram.com\/golfinhorotador\/","https:\/\/www.youtube.com\/channel\/UCYw-aMfBHbkUU_DimpWJzbw","https:\/\/www.tiktok.com\/@golfinhorotador"]},{"@type":"Person","@id":"https:\/\/golfinhorotador.org.br\/#\/schema\/person\/31c9f545fc127c9e21fc1c5f001269db","name":"Projeto Golfinho Rotador","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g","caption":"Projeto Golfinho Rotador"},"url":"https:\/\/golfinhorotador.org.br\/en\/author\/projeto-golfinho-rotador\/"}]}},"_links":{"self":[{"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts\/874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/comments?post=874"}],"version-history":[{"count":2,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts\/874\/revisions"}],"predecessor-version":[{"id":877,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts\/874\/revisions\/877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/media\/875"}],"wp:attachment":[{"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/media?parent=874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/categories?post=874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/tags?post=874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}